{"id":441,"date":"2011-04-17T16:22:39","date_gmt":"2011-04-17T14:22:39","guid":{"rendered":"http:\/\/www.coeurssansfrontieres.com\/vie-de-lassociation\/rencontres\/versammlung-2-april-2011-im-strasbourg\/"},"modified":"2017-10-07T15:25:52","modified_gmt":"2017-10-07T13:25:52","slug":"versammlung-2-april-2011-im-strasbourg","status":"publish","type":"post","link":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/","title":{"rendered":"Versammlung 2 April 2011 im Strasbourg"},"content":{"rendered":"<p>[et_pb_section admin_label=&#8220;section&#8220;][et_pb_row admin_label=&#8220;row&#8220;][et_pb_column type=&#8220;4_4&#8243;][et_pb_text admin_label=&#8220;Texte&#8220;]<\/p>\n<p>Die deutschen und franz\u00f6sischen Mitglieder (Nord-Ostregion) haben sich am 2. April 2011 in Stra\u00dfburg versammelt.<\/p>\n<p>&nbsp;<\/p>\n<p>Eine herzliche und br\u00fcderliche Stimmung war den ganzen Tag zu sp\u00fcren . Sofort hat jeder sich verstanden gef\u00fchlt und sich integriert . Zufrieden Gleichartige zu treffen und getr\u00f6stet zu merken, dass es leicht ist, seine pers\u00f6nliche Geschichte denen zu erz\u00e4hlen, die wie sie, wegen des 2.Weltkrieg ihre v\u00e4terliche Wurzeln nicht kennen. Und haben einen m\u00fchsamen Weg angefangen, um zu wissen wem sie ihr Leben verdanken.<\/p>\n<p>&nbsp;<\/p>\n<p>Reden nach jahrelanger Stille, endlich raus aus dem Tabu ist ein Schritt zum sich besser zu f\u00fchlen der Kinder des Krieges.<\/p>\n<p>Der Tag war durch starke Momente unterstrichen:<\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"font-size: 14pt;\">&#8211;<\/span><\/strong> Herr Gasparetto ein \u201cMalgre-nous\u201d gegen seinen Willen in der Wehrmacht eingerollt , hat uns zum manchmal schrecklichen Leben der K\u00e4mpfer des 2.Weltkrieg transportiert.<\/p>\n<p>&nbsp;<\/p>\n<p>Danke an ihn . Es ist sehr wichtig, dass das einzelne Los unserer V\u00e4ter, ganz, wie sich unsere durch den Krieg bedingten Schwierigkeiten in der Geschichte mit einem Gro\u00dfen H nicht untergehen.<\/p>\n<p>Der Krieg ist eine Summe von gegens\u00e4tzlichen Schicksalen und von den Schmerzen, die mehreren Generationen andauern. Es ist wichtig, es auszusprechen, um zu versuchen, uns gegen diese Gei\u00dfel zu garantieren.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-438\" src=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026A.jpg\" width=\"450\" height=\"311\" border=\"0\" srcset=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026A.jpg 450w, https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026A-300x207.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>&#8211; Das 1.Treffen von der deutschen Elke mit ihrer franz\u00f6sischen Schwester. Elkes Vater war bei der franz\u00f6sischen Armee in Deutschland.<\/p>\n<p>&nbsp;<\/p>\n<p>Welche Ersch\u00fctterung ! Diese Schwestern die total unwissend ,dass e seine Schwester gab \u2013 erzogen wurden, sind sich so \u00e4hnlich, dass sie einen fast gleichen Beruf gew\u00e4hlt haben.<\/p>\n<p>&nbsp;<\/p>\n<p>Dieser Beweis einer M\u00f6glichkeit des Findens hat jeden Teilnehmer motivieren, seine Nachforschung mit Hoffnung fortzusetzen.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-439\" src=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026B.jpg\" width=\"450\" height=\"306\" border=\"0\" srcset=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026B.jpg 450w, https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026B-300x204.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>Vorne rechts Elke, gegen\u00fcber ihre Schwester -Neben Elke ist Frau Gasparetto Psychologin und \u00dcbersetzerin<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; Besuch von Herrn Elkouby allgemeiner Ratgeber und Stellvertreter des B\u00fcrgermeisters von Stra\u00dfburg. Herr Elkouby zeigte sich von der Aktivit\u00e4t von Herzen ohne Grenzen und den erhaltenen Ergebnissen interessiert.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-440\" src=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026C.jpg\" alt=\"110312LQ026C\" width=\"450\" height=\"324\" border=\"0\" srcset=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026C.jpg 450w, https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026C-300x216.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>Herr Elkouby 2. von links<\/p>\n<p>&nbsp;<\/p>\n<p><em>&#8211; Frau Marie Brassard-Goeg von der Zeitung Nouvelle D\u00e9p\u00e9che d\u2019Alsace<\/em> hat einen Artikel geschrieben, der diese sch\u00f6ne Begegnung in ihrem so historischen wie menschlichen Zusammenhang stellt.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die deutschen und franz\u00f6sischen Mitglieder (Nord-Ostregion) haben sich am 2. April 2011 in Stra\u00dfburg versammelt. &nbsp; Eine herzliche und br\u00fcderliche Stimmung war den ganzen Tag zu sp\u00fcren . Sofort hat jeder sich verstanden gef\u00fchlt und sich integriert . Zufrieden Gleichartige zu treffen und getr\u00f6stet zu merken, dass es leicht ist, seine pers\u00f6nliche Geschichte denen zu [&hellip;]<\/p>\n","protected":false},"author":249,"featured_media":438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p><strong>Les adh\u00e9rents allemands et fran\u00e7ais (r\u00e9gion Nord et Est) se sont r\u00e9unis \u00e0 Strasbourg le 2 avril 2011.<\/strong><\/p><p>Une ambiance fraternelle et chaleureuse s\u2019est d\u00e9gag\u00e9e tout au long de la journ\u00e9e. Imm\u00e9diatement chacun s\u2019est senti compris et int\u00e9gr\u00e9, content de rencontrer ses semblables et r\u00e9confort\u00e9 de constater qu\u2019il est facile, d\u2019enfin raconter son histoire personnelle \u00e0 ceux qui comme soi, ignorant en raison de la Seconde Guerre mondiale leurs racines paternelles ont entam\u00e9 un laborieux parcours pour tenter de savoir enfin \u00e0 qui ils doivent la vie.<\/p><p>Parler apr\u00e8s des ann\u00e9es de silence, enfin sortir de l\u2019enfermement du tabou est un des pas vers le mieux \u00eatre des enfants de la guerre.<\/p><p>La journ\u00e9e fut ponctu\u00e9e de moments forts :<\/p><p><strong>-<\/strong> Monsieur Gasparetto, \u00ab Malgr\u00e9-nous \u00bb enr\u00f4l\u00e9 de force dans la Wehrmacht, par son t\u00e9moignage nous a transport\u00e9 vers la vie parfois terrible des combattants de la Seconde Guerre Mondiale.<\/p><p>Merci \u00e0 lui, il est si important que le sort individuel de nos p\u00e8res, tout comme nos difficult\u00e9s dues \u00e0 la guerre ne se noient pas dans l\u2019Histoire avec un grand H.<\/p><p>La guerre est une somme de destins contrari\u00e9s et de souffrances qui se perp\u00e9tuent sur plusieurs g\u00e9n\u00e9rations. Il est capital de l\u2019\u00e9noncer pour tenter de nous garantir contre ce fl\u00e9au.<\/p><p><img class=\" size-full wp-image-435\" src=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026A.jpg\" alt=\"strasbourg 1\" width=\"450\" height=\"311\" border=\"0\" \/><\/p><p>- La 1\u00e8re rencontre d\u2019Elke allemande avec sa s\u0153ur fran\u00e7aise.<\/p><p>Le p\u00e8re d\u2019Elke faisait parti des Forces Fran\u00e7aises en Allemagne.<\/p><p>Quelle \u00e9motion ! Ces s\u0153urs \u00e9lev\u00e9es dans l\u2019ignorance l\u2019une de l\u2019autre, se ressemblent tant, au point m\u00eame d\u2019avoir choisi une orientation professionnelle semblable.<\/p><p>Ce t\u00e9moignage du possible d\u2019aussi belles retrouvailles \u00e0 motiver chaque participant pour continuer avec foi sa recherche identitaire.<\/p><p><img src=\"images\/stories\/110312LQ026B.JPG\" alt=\"strasbourg 2\" border=\"0\" \/><\/p><p>Au premier plan \u00e0 droite Elke, en face sa s\u0153ur,<\/p><p>\u00e0 c\u00f4t\u00e9 d\u2019Elke Mme Gasparetto, psychologue et traductrice<\/p><p>- Visite de Monsieur Eric ElKOUBY Conseiller g\u00e9n\u00e9ral et adjoint au maire de Strasbourg,<\/p><p>Monsieur Elkouby se d\u00e9clare int\u00e9ress\u00e9 par l\u2019activit\u00e9 de C\u0153urs sans Fronti\u00e8res et les r\u00e9sultats obtenus.<\/p><p><img src=\"images\/stories\/110312LQ026C.JPG\" alt=\"strasbourg 3\" border=\"0\" \/><\/p><p>Monsieur Elkouby : 2\u00e8me en partant de la gauche<\/p><p>- Madame Marie BRASSARD-GOEG de la Nouvelle D\u00e9p\u00eache d\u2019Alsace<\/p><p>r\u00e9dige un article qui place cette belle rencontre tant dans son contexte tant historique qu\u2019humain.<\/p><p><img class=\" size-full wp-image-436\" src=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026D.jpg\" alt=\"strasbourg 4\" width=\"400\" height=\"850\" border=\"0\" \/><\/p><p>L'Allemande Elke, 54 ans, a rencontr\u00e9 pour la premi\u00e8re fois \u00e0 Strasbourg sa demi-soeur,<\/p><p>la Fran\u00e7aise V\u00e9ronique, 43 ans, gr\u00e2ce \u00e0 l'association \u00ab Coeurs sans fronti\u00e8res \u00bb.<\/p><p><strong>La qu\u00eate du p\u00e8re <\/strong><\/p><p>L'Allemande Elke, 54 ans, a rencontr\u00e9 pour la premi\u00e8re fois \u00e0 Strasbourg sa demi-soeur, la Fran\u00e7aise V\u00e9ronique, 43 ans, gr\u00e2ce \u00e0 l'association \u00abCoeurs sans fronti\u00e8res\u00bb.<\/p><p>\u00c0 certaines tables on parlait allemand, \u00e0 d'autres fran\u00e7ais et \u00e0 d'autres encore, les deux langues... Le week-end dernier, l'association Coeurs sans fronti\u00e8res, dont la mission est d'aider les recherches des enfants franco-allemands de la Seconde Guerre mondiale, tenait sa premi\u00e8re r\u00e9union dans un h\u00f4tel strasbourgeois.<\/p><p>L'h\u00f4tel se trouve en bordure de l'Ill qui se jette dans le Rhin, si longtemps consid\u00e9r\u00e9 comme une fronti\u00e8re entre deux pays marqu\u00e9s politiquement par la haine durant trois guerres au XXe si\u00e8cle...<\/p><p>Pourtant, parce que sous les uniformes battent des coeurs d'homme, bien des soldats fran\u00e7ais et allemands ont nou\u00e9 des relations amoureuses dans le pays qui n'\u00e9tait pas le leur.<\/p><p>Des milliers d'enfants sont ainsi n\u00e9s, pas vraiment g\u00e2t\u00e9s par le sort. De longues ann\u00e9es, ils et elles ont mis \u00e0 se construire. Et \u00e0 l'heure de la retraite, justement alors qu'Internet ignore les fronti\u00e8res, ils partent \u00e0 la qu\u00eate du p\u00e8re.<\/p><p>Le myst\u00e9rieuxlien filial<\/p><p>Franck Roland est le correspondant pour le grand Est de l'association : \u00ab Du c\u00f4t\u00e9 allemand, quand on veut faire des recherches, c'est plus facile, plus ouvert. En France, il y a encore beaucoup de r\u00e9ticences, on ne veut pas de Boche dans la famille ai-je entendu. Ou alors c'est l'incompr\u00e9hension totale de la d\u00e9marche. Comme dans cette famille bourgeoise qui a propos\u00e9 de faire un ch\u00e8que quand je leur ai parl\u00e9 d'une Allemande qui pensait avoir retrouv\u00e9 son p\u00e8re. Elle \u00e9tait m\u00e9decin \u00e0 Leipzig et elle croyait au contraire que son p\u00e8re \u00e9tait pauvre... \u00bb<\/p><p>B\u00e9atrice et Monika sont motiv\u00e9es par autre chose de plus puissant que l'argent, le myst\u00e9rieux lien filial. B\u00e9atrice, n\u00e9e en 1946 \u00e0 Gengenbach, a une photo d'un jeune militaire fran\u00e7ais. Il s'appelait Raymond et il \u00e9tait stationn\u00e9 avec son r\u00e9giment \u00e0 Ortenberg : \u00ab Ma m\u00e8re est tr\u00e8s \u00e2g\u00e9e, pour elle c'est un secret de famille, elle n'en parle pas. \u00bb<\/p><p>Les archives des militaires fran\u00e7ais des troupes d'occupation sont inaccessibles. Monika, pr\u00e9nomm\u00e9e Jeannette \u00e0 sa naissance par son p\u00e8re fran\u00e7ais qui l'avait reconnue, a des photos d'elle-m\u00eame \u00e0 18 mois avec ce p\u00e8re, cavalier \u00e9m\u00e9rite sur une autre photo : \u00ab Heureusement que ma grand-m\u00e8re les avait gard\u00e9es, ma m\u00e8re avait tout d\u00e9truit \u00bb. Monika, 65 ans, sait que son p\u00e8re, Pierre Marchal, est d\u00e9c\u00e9d\u00e9 \u00e0 Nancy voici 7 ans. Elle voudrait tant savoir quel caract\u00e8re il avait, ce qu'il aimait faire... Elle, fille unique apr\u00e8s avoir \u00e9t\u00e9 adopt\u00e9e, r\u00eave de rencontrer un demi-fr\u00e8re ou une demi-soeur : \u00ab J'ai une fille qui sait parler fran\u00e7ais, ce serait bien d'entrer en contact avec la famille fran \u00e7aise... \u00bb<\/p><p>\u00ab Nous faisons l'Europe \u00bb<\/p><p>Les recherches en Allemagne ont \u00e9t\u00e9 effectu\u00e9es gr\u00e2ce au VKSVG e. V, Verein zur Kl\u00e4rung von Schiksalen Vermisster und Gefallener, une association pour d\u00e9couvrir les destins des disparus et tomb\u00e9s au front et dont la devise est \u00ab Surmonter le pass\u00e9 \u00bb. Qui travaille main dans la main avec \u00ab Coeurs sans fronti\u00e8res \u00bb dont Franck Roland dit \u00ab Nous faisons l'Europe \u00bb.<\/p><p>Avec plus d'\u00e9motion que les instances officielles comme samedi, lors de la rencontre entre deux demi-soeurs, V\u00e9ronique, la Fran\u00e7aise, et Elke, l'Allemande de Fribourg...<\/p><p>Elke est n\u00e9e en 1957. \u00ab J'ai cherch\u00e9 mon p\u00e8re pendant longtemps, en faisant des pauses. J'avais une photo de lui et son identit\u00e9 \u00bb raconte-t-elle. La recherche a abouti assez vite. La bonne surprise, c'est que l'\u00e9cho, c\u00f4t\u00e9 fran\u00e7ais, a \u00e9t\u00e9 positif. Il y a eu des mails en anglais et l'aide, lors de la rencontre, de la psychologue Mich\u00e8le Gasparato, comme interpr\u00e8te b\u00e9n\u00e9vole.<\/p><p>Co\u00efncidence<\/p><p>V\u00e9ronique, n\u00e9e en 1968, vit \u00e0 Reims et a un fr\u00e8re. Son p\u00e8re, ancien militaire, sait qu'elle a accept\u00e9 de rencontrer sa demi-soeur pour la premi\u00e8re fois \u00e0 Strasbourg : \u00ab C'est forc\u00e9ment un choc pour une famille. On voit des choses qui se passent dans des films mais quand \u00e7a arrive dans sa vie... Est-ce que mon p\u00e8re rencontrera Elke ? On a fait connaissance depuis un mois, les chose s \u00e9voluent, on verra bien... \u00bb<\/p><p>Co\u00efncidence entre ces demi-soeurs qui se ressemblent assez avec leur allure d\u00e9contract\u00e9e, la Fran\u00e7aise est formatrice d'assistantes sociales tandis que l'Allemande est assistante sociale.<\/p><p><strong>Marie Brassart-Goerg <\/strong><\/p><p>Coeur sans fronti\u00e8res, association franco-allemande des enfants de la Seconde Guerre mondiale, www.coeurssansfrontieres.com ou 06 18 99 50 72, Chantal Le Quentrec, d\u00e9l\u00e9gu\u00e9e r\u00e9gionale Allemagne-Autriche<\/p>","_et_gb_content_width":"","footnotes":""},"categories":[155,14],"tags":[],"class_list":["post-441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regionaltreffen","category-vereinsleben"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Versammlung 2 April 2011 im Strasbourg - CSF - HOG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Versammlung 2 April 2011 im Strasbourg - CSF - HOG\" \/>\n<meta property=\"og:description\" content=\"Die deutschen und franz\u00f6sischen Mitglieder (Nord-Ostregion) haben sich am 2. April 2011 in Stra\u00dfburg versammelt. &nbsp; Eine herzliche und br\u00fcderliche Stimmung war den ganzen Tag zu sp\u00fcren . Sofort hat jeder sich verstanden gef\u00fchlt und sich integriert . Zufrieden Gleichartige zu treffen und getr\u00f6stet zu merken, dass es leicht ist, seine pers\u00f6nliche Geschichte denen zu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/\" \/>\n<meta property=\"og:site_name\" content=\"CSF - HOG\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-17T14:22:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-07T13:25:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026A.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"311\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GOFFIN Alexandre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"GOFFIN Alexandre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/vereinsleben\\\/regionaltreffen\\\/versammlung-2-april-2011-im-strasbourg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/vereinsleben\\\/regionaltreffen\\\/versammlung-2-april-2011-im-strasbourg\\\/\"},\"author\":{\"name\":\"GOFFIN Alexandre\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#\\\/schema\\\/person\\\/19507754554eb5218427fc31038cac56\"},\"headline\":\"Versammlung 2 April 2011 im Strasbourg\",\"datePublished\":\"2011-04-17T14:22:39+00:00\",\"dateModified\":\"2017-10-07T13:25:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/vereinsleben\\\/regionaltreffen\\\/versammlung-2-april-2011-im-strasbourg\\\/\"},\"wordCount\":400,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/vereinsleben\\\/regionaltreffen\\\/versammlung-2-april-2011-im-strasbourg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/110312LQ026A.jpg\",\"articleSection\":[\"Regionaltreffen\",\"Vereinsleben\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/vereinsleben\\\/regionaltreffen\\\/versammlung-2-april-2011-im-strasbourg\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/vereinsleben\\\/regionaltreffen\\\/versammlung-2-april-2011-im-strasbourg\\\/\",\"url\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/vereinsleben\\\/regionaltreffen\\\/versammlung-2-april-2011-im-strasbourg\\\/\",\"name\":\"Versammlung 2 April 2011 im Strasbourg - CSF - HOG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/vereinsleben\\\/regionaltreffen\\\/versammlung-2-april-2011-im-strasbourg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/vereinsleben\\\/regionaltreffen\\\/versammlung-2-april-2011-im-strasbourg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/110312LQ026A.jpg\",\"datePublished\":\"2011-04-17T14:22:39+00:00\",\"dateModified\":\"2017-10-07T13:25:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#\\\/schema\\\/person\\\/19507754554eb5218427fc31038cac56\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/vereinsleben\\\/regionaltreffen\\\/versammlung-2-april-2011-im-strasbourg\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/vereinsleben\\\/regionaltreffen\\\/versammlung-2-april-2011-im-strasbourg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/vereinsleben\\\/regionaltreffen\\\/versammlung-2-april-2011-im-strasbourg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/110312LQ026A.jpg\",\"contentUrl\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/110312LQ026A.jpg\",\"width\":450,\"height\":311},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/vereinsleben\\\/regionaltreffen\\\/versammlung-2-april-2011-im-strasbourg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Versammlung 2 April 2011 im Strasbourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/\",\"name\":\"C\u0153urs sans fronti\u00e8res\",\"description\":\"Association franco-allemande des Enfants de la Seconde Guerre Mondiale\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#\\\/schema\\\/person\\\/19507754554eb5218427fc31038cac56\",\"name\":\"GOFFIN Alexandre\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Versammlung 2 April 2011 im Strasbourg - CSF - HOG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/","og_locale":"de_DE","og_type":"article","og_title":"Versammlung 2 April 2011 im Strasbourg - CSF - HOG","og_description":"Die deutschen und franz\u00f6sischen Mitglieder (Nord-Ostregion) haben sich am 2. April 2011 in Stra\u00dfburg versammelt. &nbsp; Eine herzliche und br\u00fcderliche Stimmung war den ganzen Tag zu sp\u00fcren . Sofort hat jeder sich verstanden gef\u00fchlt und sich integriert . Zufrieden Gleichartige zu treffen und getr\u00f6stet zu merken, dass es leicht ist, seine pers\u00f6nliche Geschichte denen zu [&hellip;]","og_url":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/","og_site_name":"CSF - HOG","article_published_time":"2011-04-17T14:22:39+00:00","article_modified_time":"2017-10-07T13:25:52+00:00","og_image":[{"width":450,"height":311,"url":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026A.jpg","type":"image\/jpeg"}],"author":"GOFFIN Alexandre","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"GOFFIN Alexandre","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/#article","isPartOf":{"@id":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/"},"author":{"name":"GOFFIN Alexandre","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#\/schema\/person\/19507754554eb5218427fc31038cac56"},"headline":"Versammlung 2 April 2011 im Strasbourg","datePublished":"2011-04-17T14:22:39+00:00","dateModified":"2017-10-07T13:25:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/"},"wordCount":400,"commentCount":0,"image":{"@id":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026A.jpg","articleSection":["Regionaltreffen","Vereinsleben"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/","url":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/","name":"Versammlung 2 April 2011 im Strasbourg - CSF - HOG","isPartOf":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/#primaryimage"},"image":{"@id":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026A.jpg","datePublished":"2011-04-17T14:22:39+00:00","dateModified":"2017-10-07T13:25:52+00:00","author":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#\/schema\/person\/19507754554eb5218427fc31038cac56"},"breadcrumb":{"@id":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/#primaryimage","url":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026A.jpg","contentUrl":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2011\/04\/110312LQ026A.jpg","width":450,"height":311},{"@type":"BreadcrumbList","@id":"https:\/\/www.coeurssansfrontieres.com\/de\/vereinsleben\/regionaltreffen\/versammlung-2-april-2011-im-strasbourg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.coeurssansfrontieres.com\/de\/"},{"@type":"ListItem","position":2,"name":"Versammlung 2 April 2011 im Strasbourg"}]},{"@type":"WebSite","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#website","url":"https:\/\/www.coeurssansfrontieres.com\/fr\/","name":"C\u0153urs sans fronti\u00e8res","description":"Association franco-allemande des Enfants de la Seconde Guerre Mondiale","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coeurssansfrontieres.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#\/schema\/person\/19507754554eb5218427fc31038cac56","name":"GOFFIN Alexandre"}]}},"_links":{"self":[{"href":"https:\/\/www.coeurssansfrontieres.com\/de\/wp-json\/wp\/v2\/posts\/441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coeurssansfrontieres.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.coeurssansfrontieres.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/de\/wp-json\/wp\/v2\/users\/249"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/de\/wp-json\/wp\/v2\/comments?post=441"}],"version-history":[{"count":0,"href":"https:\/\/www.coeurssansfrontieres.com\/de\/wp-json\/wp\/v2\/posts\/441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/de\/wp-json\/wp\/v2\/media\/438"}],"wp:attachment":[{"href":"https:\/\/www.coeurssansfrontieres.com\/de\/wp-json\/wp\/v2\/media?parent=441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/de\/wp-json\/wp\/v2\/categories?post=441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/de\/wp-json\/wp\/v2\/tags?post=441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}