{"id":160,"date":"2008-08-06T18:00:00","date_gmt":"2008-08-06T16:00:00","guid":{"rendered":"http:\/\/www.coeurssansfrontieres.com\/vie-de-lassociation\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/"},"modified":"2017-10-09T22:47:02","modified_gmt":"2017-10-09T20:47:02","slug":"rendez-vous-a-nantes-apres-63-ans","status":"publish","type":"post","link":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/","title":{"rendered":"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans"},"content":{"rendered":"<p>[et_pb_section admin_label=\u00a0\u00bbsection\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime;][et_pb_text admin_label=\u00a0\u00bbTexte\u00a0\u00bb]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-159\" title=\"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans\" src=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2008\/08\/nantes.jpg\" alt=\"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans\" width=\"540\" height=\"200\" align=\"right\" border=\"1\" hspace=\"20\" vspace=\"20\" srcset=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2008\/08\/nantes.jpg 540w, https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2008\/08\/nantes-480x178.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 540px, 100vw\" \/><\/p>\n<p><strong>Johanna Brunne, n\u00e9e Madd\u00e9e<\/strong><\/p>\n<p class=\"MsoNormal\">A la recherche de mon p\u00e8re, de sa tombe, de mon identit\u00e9, de mes racines en France, c&rsquo;est une famille accueillante et harmonieuse que j&rsquo;ai trouv\u00e9e ! Je lui ai rendu visite pour la premi\u00e8re fois en novembre 2006, et je crois que j&rsquo;ai r\u00e9ussi, dans ce petit cercle priv\u00e9, mon examen d\u2019int\u00e9gration&#8230;<\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\"><strong>Jacqueline et Johanna<\/strong><\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\">Je savais depuis mon enfance que mon papa \u00e9tait un prisonnier de guerre fran\u00e7ais et qu\u2019il avait travaill\u00e9 avec ma m\u00e8re dans les studios de l\u2019UFA \u00e0 Babelsberg. Leur amour interdit (!) avait dur\u00e9 un peu plus d&rsquo;un an, avec toujours la guerre en toile de fond. Ma m\u00e8re \u00e9tait une Berlinoise, ses anc\u00eatres des Huguenots. Elle avait un pr\u00e9nom et un nom de famille fran\u00e7ais, elle parlait fran\u00e7ais &#8211; plus ou moins bien certes, mais ceci avait sans doute favoris\u00e9 leur liaison.<\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\">Mon p\u00e8re fut rapatri\u00e9 trois mois avant ma naissance, une chance pour lui, une trag\u00e9die pour ma m\u00e8re. Elle vivait dans l\u2019espoir de le retrouver apr\u00e8s la guerre, puisant toute son \u00e9nergie dans son amour sans borne pour cet homme qu\u2019elle avait perdu si brusquement. Au fil des ann\u00e9es, j&rsquo;ai toujours eu le sentiment \u00e0 travers elle d&rsquo;avoir \u00e9t\u00e9 une enfant d\u00e9sir\u00e9e. Elle faisait une totale abn\u00e9gation de sa personne pour me donner une enfance heureuse. Mais h\u00e9las, je ne pouvais pas partir en France \u00e0 la recherche de ce papa id\u00e9alis\u00e9 et tant aim\u00e9 en secret.<\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\">Nous vivions \u00e0 Berlin-Est, en ex-R.D.A. Je ne poss\u00e9dais qu&rsquo;une photo de lui, je connaissais son nom exact, sa date de naissance approximative, mais je n&rsquo;avais aucune adresse pr\u00e9cise, juste la ville d&rsquo;Arcachon, o\u00f9 il \u00e9tait retourn\u00e9 fin 1942. Les tentatives entreprises par ma m\u00e8re pour le retrouver, dans les ann\u00e9es pr\u00e9c\u00e9dant la construction du mur, par l\u2019interm\u00e9diaire du Consulat fran\u00e7ais, \u00e9chou\u00e8rent. Son camarade de guerre \u00e0 Paris ne savait rien de pr\u00e9cis non plus. Je m\u2019\u00e9tais donc r\u00e9sign\u00e9e, depuis longtemps&#8230;<\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\">Et puis, apr\u00e8s avoir lu le livre \u00ab\u00a0Enfants maudits\u201c de Jean-Paul Picaper et Ludwig Norz, je pris contact avec eux, leur disant que je faisais partie de ces \u00ab enfants de guerre \u00bb, mais n\u00e9e d\u2019un p\u00e8re fran\u00e7ais et d\u2019une m\u00e8re allemande. Ils m&rsquo;encourag\u00e8rent, en f\u00e9vrier 2006, \u00e0 pr\u00e9senter une demande de paternit\u00e9 aupr\u00e8s du service de renseignements sur la Wehrmacht (la WASt) \u00e0 Berlin. Ce que je fis. Et l\u00e0, l&rsquo;espoir et l&rsquo;excitation revinrent en force lorsque je re\u00e7us un premier appel de la WASt me disant que dans un des dossiers, align\u00e9s par milliers, se trouvait une fiche avec le signalement d&rsquo;un homme pouvant correspondre \u00e0 celui de mon p\u00e8re. H\u00e9las, ce fut une fausse joie. Cet homme n&rsquo;\u00e9tait pas mon p\u00e8re.<\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\">La bonne nouvelle arriva en juin 2006 des archives militaires de Caen. L\u00e0, tout \u00e9tait \u00e9tait minutieusement enregistr\u00e9, de sa date d&rsquo;arrestation en Juin 1940 sur la Somme \u00e0 son emploi dans les studios de l\u2019UFA \u00e0 Babelsberg en Allemagne, jusqu&rsquo;\u00e0 la date et au lieu de sa mort. J&rsquo;appris que j&rsquo;avais deux demi-soeurs, Janine et Jacqueline. Comment les retrouver ? Elles ne portaient sans doute plus leur nom de jeune fille. C&rsquo;est ici qu&rsquo;intervint la solidarit\u00e9 active de l\u2019association \u201eC\u0153urs sans Fronti\u00e8res-Herzen ohne Grenzen\u201c. Son pr\u00e9sident, Jean-Jacques Delorme, fut alors mon \u201eSherlock Holmes\u201c. Il sacrifia du temps \u00e0 son cong\u00e9 d\u2019\u00e9t\u00e9 en Bretagne pour essayer de retrouver, dans un premier temps, la tombe de mon p\u00e8re. Et de l\u00e0, se mettre sur la piste de mes demi-soeurs. Il se renseigna \u00e0 la mairie pour conna\u00eetre le nom des descendants de mon p\u00e8re et apr\u00e8s s&rsquo;\u00eatre annonc\u00e9 par t\u00e9l\u00e9phone,\u00a0 il rendit visite \u00e0 ma demi-s\u0153ur Jacqueline pour lui apprendre, avec toute la d\u00e9licatesse que suppose une telle r\u00e9v\u00e9lation, qu&rsquo;elle avait une demi-soeur en Allemagne ! La surprise pass\u00e9e, c&rsquo;est avec la sagesse de l&rsquo;\u00e2ge qu&rsquo;elle int\u00e9gra cette nouvelle.<\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\">Maintenant je sais que je n&rsquo;ai pas \u00e9tudi\u00e9 en vain la langue de mon p\u00e8re. Nous avons plong\u00e9, ma soeur et moi, au plus profond de ce pass\u00e9 lointain. Et c&rsquo;est sereines que nous en sommes ressorties, donnant \u00e0 notre p\u00e8re d\u00e9funt notre absolution commune.<\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\">Je me suis recueillie sur sa tombe, et j&rsquo;ai eu une t\u00eate-\u00e0-t\u00eate paisible avec lui. Loin de moi l&rsquo;id\u00e9e de troubler sa famille, mais apr\u00e8s l&rsquo;accueil chaleureux et \u00e9mouvant que j&rsquo;ai re\u00e7u de tous ses membres, nous souhaitons poursuivre et pr\u00e9server cette nouvelle relation dans l&rsquo;avenir. Pour mon plus grand bonheur !<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Johanna Brunne, n\u00e9e Madd\u00e9e A la recherche de mon p\u00e8re, de sa tombe, de mon identit\u00e9, de mes racines en France, c&rsquo;est une famille accueillante et harmonieuse que j&rsquo;ai trouv\u00e9e ! Je lui ai rendu visite pour la premi\u00e8re fois en novembre 2006, et je crois que j&rsquo;ai r\u00e9ussi, dans ce petit cercle priv\u00e9, mon [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":159,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p><img class=\" alignright size-full wp-image-159\" title=\"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans\" src=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2008\/08\/nantes.jpg\" alt=\"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans\" width=\"540\" height=\"200\" align=\"right\" border=\"1\" hspace=\"20\" vspace=\"20\" \/><\/p><p><strong>Johanna Brunne, n\u00e9e Madd\u00e9e<\/strong><\/p><p class=\"MsoNormal\">A la recherche de mon p\u00e8re, de sa tombe, de mon identit\u00e9, de mes racines en France, c'est une famille accueillante et harmonieuse que j'ai trouv\u00e9e ! Je lui ai rendu visite pour la premi\u00e8re fois en novembre 2006, et je crois que j'ai r\u00e9ussi, dans ce petit cercle priv\u00e9, mon examen d\u2019int\u00e9gration...<\/p><p class=\"MsoNormal\">\u00a0<\/p><p class=\"MsoNormal\"><strong>Jacqueline et Johanna<\/strong><\/p><p class=\"MsoNormal\">\u00a0<\/p><p class=\"MsoNormal\">Je savais depuis mon enfance que mon papa \u00e9tait un prisonnier de guerre fran\u00e7ais et qu\u2019il avait travaill\u00e9 avec ma m\u00e8re dans les studios de l\u2019UFA \u00e0 Babelsberg. Leur amour interdit (!) avait dur\u00e9 un peu plus d'un an, avec toujours la guerre en toile de fond. Ma m\u00e8re \u00e9tait une Berlinoise, ses anc\u00eatres des Huguenots. Elle avait un pr\u00e9nom et un nom de famille fran\u00e7ais, elle parlait fran\u00e7ais - plus ou moins bien certes, mais ceci avait sans doute favoris\u00e9 leur liaison.<\/p><p class=\"MsoNormal\">\u00a0<\/p><p class=\"MsoNormal\">Mon p\u00e8re fut rapatri\u00e9 trois mois avant ma naissance, une chance pour lui, une trag\u00e9die pour ma m\u00e8re. Elle vivait dans l\u2019espoir de le retrouver apr\u00e8s la guerre, puisant toute son \u00e9nergie dans son amour sans borne pour cet homme qu\u2019elle avait perdu si brusquement. Au fil des ann\u00e9es, j'ai toujours eu le sentiment \u00e0 travers elle d'avoir \u00e9t\u00e9 une enfant d\u00e9sir\u00e9e. Elle faisait une totale abn\u00e9gation de sa personne pour me donner une enfance heureuse. Mais h\u00e9las, je ne pouvais pas partir en France \u00e0 la recherche de ce papa id\u00e9alis\u00e9 et tant aim\u00e9 en secret.<\/p><p class=\"MsoNormal\">\u00a0<\/p><p class=\"MsoNormal\">Nous vivions \u00e0 Berlin-Est, en ex-R.D.A. Je ne poss\u00e9dais qu'une photo de lui, je connaissais son nom exact, sa date de naissance approximative, mais je n'avais aucune adresse pr\u00e9cise, juste la ville d'Arcachon, o\u00f9 il \u00e9tait retourn\u00e9 fin 1942. Les tentatives entreprises par ma m\u00e8re pour le retrouver, dans les ann\u00e9es pr\u00e9c\u00e9dant la construction du mur, par l\u2019interm\u00e9diaire du Consulat fran\u00e7ais, \u00e9chou\u00e8rent. Son camarade de guerre \u00e0 Paris ne savait rien de pr\u00e9cis non plus. Je m\u2019\u00e9tais donc r\u00e9sign\u00e9e, depuis longtemps...<\/p><p class=\"MsoNormal\">\u00a0<\/p><p class=\"MsoNormal\">Et puis, apr\u00e8s avoir lu le livre \"Enfants maudits\u201c de Jean-Paul Picaper et Ludwig Norz, je pris contact avec eux, leur disant que je faisais partie de ces \u00ab enfants de guerre \u00bb, mais n\u00e9e d\u2019un p\u00e8re fran\u00e7ais et d\u2019une m\u00e8re allemande. Ils m'encourag\u00e8rent, en f\u00e9vrier 2006, \u00e0 pr\u00e9senter une demande de paternit\u00e9 aupr\u00e8s du service de renseignements sur la Wehrmacht (la WASt) \u00e0 Berlin. Ce que je fis. Et l\u00e0, l'espoir et l'excitation revinrent en force lorsque je re\u00e7us un premier appel de la WASt me disant que dans un des dossiers, align\u00e9s par milliers, se trouvait une fiche avec le signalement d'un homme pouvant correspondre \u00e0 celui de mon p\u00e8re. H\u00e9las, ce fut une fausse joie. Cet homme n'\u00e9tait pas mon p\u00e8re.<\/p><p class=\"MsoNormal\">\u00a0<\/p><p class=\"MsoNormal\">La bonne nouvelle arriva en juin 2006 des archives militaires de Caen. L\u00e0, tout \u00e9tait \u00e9tait minutieusement enregistr\u00e9, de sa date d'arrestation en Juin 1940 sur la Somme \u00e0 son emploi dans les studios de l\u2019UFA \u00e0 Babelsberg en Allemagne, jusqu'\u00e0 la date et au lieu de sa mort. J'appris que j'avais deux demi-soeurs, Janine et Jacqueline. Comment les retrouver ? Elles ne portaient sans doute plus leur nom de jeune fille. C'est ici qu'intervint la solidarit\u00e9 active de l\u2019association \u201eC\u0153urs sans Fronti\u00e8res-Herzen ohne Grenzen\u201c. Son pr\u00e9sident, Jean-Jacques Delorme, fut alors mon \u201eSherlock Holmes\u201c. Il sacrifia du temps \u00e0 son cong\u00e9 d\u2019\u00e9t\u00e9 en Bretagne pour essayer de retrouver, dans un premier temps, la tombe de mon p\u00e8re. Et de l\u00e0, se mettre sur la piste de mes demi-soeurs. Il se renseigna \u00e0 la mairie pour conna\u00eetre le nom des descendants de mon p\u00e8re et apr\u00e8s s'\u00eatre annonc\u00e9 par t\u00e9l\u00e9phone,\u00a0 il rendit visite \u00e0 ma demi-s\u0153ur Jacqueline pour lui apprendre, avec toute la d\u00e9licatesse que suppose une telle r\u00e9v\u00e9lation, qu'elle avait une demi-soeur en Allemagne ! La surprise pass\u00e9e, c'est avec la sagesse de l'\u00e2ge qu'elle int\u00e9gra cette nouvelle.<\/p><p class=\"MsoNormal\">\u00a0<\/p><p class=\"MsoNormal\">Maintenant je sais que je n'ai pas \u00e9tudi\u00e9 en vain la langue de mon p\u00e8re. Nous avons plong\u00e9, ma soeur et moi, au plus profond de ce pass\u00e9 lointain. Et c'est sereines que nous en sommes ressorties, donnant \u00e0 notre p\u00e8re d\u00e9funt notre absolution commune.<\/p><p class=\"MsoNormal\">\u00a0<\/p><p class=\"MsoNormal\">Je me suis recueillie sur sa tombe, et j'ai eu une t\u00eate-\u00e0-t\u00eate paisible avec lui. Loin de moi l'id\u00e9e de troubler sa famille, mais apr\u00e8s l'accueil chaleureux et \u00e9mouvant que j'ai re\u00e7u de tous ses membres, nous souhaitons poursuivre et pr\u00e9server cette nouvelle relation dans l'avenir. Pour mon plus grand bonheur !<\/p>","_et_gb_content_width":"","footnotes":""},"categories":[159,28],"tags":[],"class_list":["post-160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recherches","category-retrouvailles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans - CSF - HOG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans - CSF - HOG\" \/>\n<meta property=\"og:description\" content=\"Johanna Brunne, n\u00e9e Madd\u00e9e A la recherche de mon p\u00e8re, de sa tombe, de mon identit\u00e9, de mes racines en France, c&#039;est une famille accueillante et harmonieuse que j&#039;ai trouv\u00e9e ! Je lui ai rendu visite pour la premi\u00e8re fois en novembre 2006, et je crois que j&#039;ai r\u00e9ussi, dans ce petit cercle priv\u00e9, mon [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/\" \/>\n<meta property=\"og:site_name\" content=\"CSF - HOG\" \/>\n<meta property=\"article:published_time\" content=\"2008-08-06T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-09T20:47:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2008\/08\/nantes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LE QUENTREC Chantal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"LE QUENTREC Chantal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/recherches\\\/retrouvailles\\\/rendez-vous-a-nantes-apres-63-ans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/recherches\\\/retrouvailles\\\/rendez-vous-a-nantes-apres-63-ans\\\/\"},\"author\":{\"name\":\"LE QUENTREC Chantal\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#\\\/schema\\\/person\\\/ae811928053aca16ba5f8ad091b75a2e\"},\"headline\":\"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans\",\"datePublished\":\"2008-08-06T16:00:00+00:00\",\"dateModified\":\"2017-10-09T20:47:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/recherches\\\/retrouvailles\\\/rendez-vous-a-nantes-apres-63-ans\\\/\"},\"wordCount\":863,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/recherches\\\/retrouvailles\\\/rendez-vous-a-nantes-apres-63-ans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/wp-content\\\/uploads\\\/2008\\\/08\\\/nantes.jpg\",\"articleSection\":[\"Recherches\",\"Retrouvailles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/recherches\\\/retrouvailles\\\/rendez-vous-a-nantes-apres-63-ans\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/recherches\\\/retrouvailles\\\/rendez-vous-a-nantes-apres-63-ans\\\/\",\"url\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/recherches\\\/retrouvailles\\\/rendez-vous-a-nantes-apres-63-ans\\\/\",\"name\":\"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans - CSF - HOG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/recherches\\\/retrouvailles\\\/rendez-vous-a-nantes-apres-63-ans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/recherches\\\/retrouvailles\\\/rendez-vous-a-nantes-apres-63-ans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/wp-content\\\/uploads\\\/2008\\\/08\\\/nantes.jpg\",\"datePublished\":\"2008-08-06T16:00:00+00:00\",\"dateModified\":\"2017-10-09T20:47:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#\\\/schema\\\/person\\\/ae811928053aca16ba5f8ad091b75a2e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/recherches\\\/retrouvailles\\\/rendez-vous-a-nantes-apres-63-ans\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/recherches\\\/retrouvailles\\\/rendez-vous-a-nantes-apres-63-ans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/recherches\\\/retrouvailles\\\/rendez-vous-a-nantes-apres-63-ans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/wp-content\\\/uploads\\\/2008\\\/08\\\/nantes.jpg\",\"contentUrl\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/wp-content\\\/uploads\\\/2008\\\/08\\\/nantes.jpg\",\"width\":540,\"height\":200,\"caption\":\"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/recherches\\\/retrouvailles\\\/rendez-vous-a-nantes-apres-63-ans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/\",\"name\":\"C\u0153urs sans fronti\u00e8res\",\"description\":\"Association franco-allemande des Enfants de la Seconde Guerre Mondiale\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#\\\/schema\\\/person\\\/ae811928053aca16ba5f8ad091b75a2e\",\"name\":\"LE QUENTREC Chantal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans - CSF - HOG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/","og_locale":"fr_FR","og_type":"article","og_title":"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans - CSF - HOG","og_description":"Johanna Brunne, n\u00e9e Madd\u00e9e A la recherche de mon p\u00e8re, de sa tombe, de mon identit\u00e9, de mes racines en France, c'est une famille accueillante et harmonieuse que j'ai trouv\u00e9e ! Je lui ai rendu visite pour la premi\u00e8re fois en novembre 2006, et je crois que j'ai r\u00e9ussi, dans ce petit cercle priv\u00e9, mon [&hellip;]","og_url":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/","og_site_name":"CSF - HOG","article_published_time":"2008-08-06T16:00:00+00:00","article_modified_time":"2017-10-09T20:47:02+00:00","og_image":[{"width":540,"height":200,"url":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2008\/08\/nantes.jpg","type":"image\/jpeg"}],"author":"LE QUENTREC Chantal","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"LE QUENTREC Chantal","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/#article","isPartOf":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/"},"author":{"name":"LE QUENTREC Chantal","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#\/schema\/person\/ae811928053aca16ba5f8ad091b75a2e"},"headline":"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans","datePublished":"2008-08-06T16:00:00+00:00","dateModified":"2017-10-09T20:47:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/"},"wordCount":863,"commentCount":0,"image":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2008\/08\/nantes.jpg","articleSection":["Recherches","Retrouvailles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/","url":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/","name":"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans - CSF - HOG","isPartOf":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/#primaryimage"},"image":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2008\/08\/nantes.jpg","datePublished":"2008-08-06T16:00:00+00:00","dateModified":"2017-10-09T20:47:02+00:00","author":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#\/schema\/person\/ae811928053aca16ba5f8ad091b75a2e"},"breadcrumb":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/#primaryimage","url":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2008\/08\/nantes.jpg","contentUrl":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2008\/08\/nantes.jpg","width":540,"height":200,"caption":"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans"},{"@type":"BreadcrumbList","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/recherches\/retrouvailles\/rendez-vous-a-nantes-apres-63-ans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.coeurssansfrontieres.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Rendez-vous \u00e0 Nantes apr\u00e8s 63 ans"}]},{"@type":"WebSite","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#website","url":"https:\/\/www.coeurssansfrontieres.com\/fr\/","name":"C\u0153urs sans fronti\u00e8res","description":"Association franco-allemande des Enfants de la Seconde Guerre Mondiale","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coeurssansfrontieres.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#\/schema\/person\/ae811928053aca16ba5f8ad091b75a2e","name":"LE QUENTREC Chantal"}]}},"_links":{"self":[{"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/posts\/160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/comments?post=160"}],"version-history":[{"count":0,"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/posts\/160\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/media\/159"}],"wp:attachment":[{"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/media?parent=160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/categories?post=160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/tags?post=160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}