{"id":622,"date":"2012-08-26T14:48:39","date_gmt":"2012-08-26T12:48:39","guid":{"rendered":"http:\/\/www.coeurssansfrontieres.com\/vie-de-lassociation\/rencontres\/reunion-montilienne\/"},"modified":"2017-10-05T16:09:42","modified_gmt":"2017-10-05T14:09:42","slug":"reunion-montilienne","status":"publish","type":"post","link":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/","title":{"rendered":"R\u00e9union Montilienne"},"content":{"rendered":"<p>[et_pb_section admin_label=\u00a0\u00bbsection\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime;][et_pb_text admin_label=\u00a0\u00bbTexte\u00a0\u00bb]<\/p>\n<p>Les adh\u00e9rents de la r\u00e9gion Sud-est se sont r\u00e9unis pour la 4<sup>\u00e8me<\/sup> ann\u00e9e cons\u00e9cutive chez leur d\u00e9l\u00e9gu\u00e9e Jeanne Vinas. Les 25 personnes pr\u00e9sentent ont contribu\u00e9 \u00e0 cette rencontre fort amicale, certains venaient de loin : Alpes-Maritimes, Gard et m\u00eame de l\u2019Yonne. Au cours de conversations fraternelles les \u00e9changes concernant les recherches en cours ont occup\u00e9 une grande partie de la journ\u00e9e. Il est si rare de pourvoir parler sans contrainte avec la certitude d\u2019\u00eatre compris !<\/p>\n<p>Un repas au restaurant et une visite au palais des bonbons (http:\/\/www.palais-bonbons.com). pour la convivialit\u00e9 et la distraction, puis h\u00e9las les au revoir et l\u2019attente avant la prochaine r\u00e9union chez Jeanne le 15 juin 2013.<\/p>\n<p><em>Quelques t\u00e9moignages :<\/em><\/p>\n<p>Un grand merci pour votre accueil chaleureux et g\u00e9n\u00e9reux. Superbe rencontre. Encore Merci. <em>Pascal<\/em>.<\/p>\n<p>Encore mille fois merci pour votre accueil et votre g\u00e9n\u00e9rosit\u00e9. La journ\u00e9e d\u2019hier \u00e9tait vraiment superbe et tr\u00e8s r\u00e9ussie. Bravo pour l\u2019organisation. Toutes les personnes pr\u00e9sentes \u00e9taient tr\u00e8s int\u00e9ressantes et l\u2019histoire de chacune est tr\u00e8s \u00e9mouvante. Nous sommes ravis de ces bons moments pass\u00e9s ensemble. A bient\u00f4t. Bien amicalement. <em>Philippe et Marie-Fran\u00e7oise<\/em><\/p>\n<p>Merci pour cet accueil si chaleureux. <em>Fernande<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-621\" title=\"120811LQ050A\" src=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2012\/08\/120811LQ050A.jpg\" alt=\"120811LQ050A\" width=\"500\" height=\"399\" border=\"1\" srcset=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2012\/08\/120811LQ050A.jpg 500w, https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2012\/08\/120811LQ050A-480x383.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 500px, 100vw\" \/><\/p>\n<p><img decoding=\"async\" src=\"file:\/\/\/D:\/Pro\/Projets%20Internet\/Sites\/CSF\/_offline\/120826\/120811LQ051A.jpg\" width=\"100%\" border=\"0\" \/><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les adh\u00e9rents de la r\u00e9gion Sud-est se sont r\u00e9unis pour la 4\u00e8me ann\u00e9e cons\u00e9cutive chez leur d\u00e9l\u00e9gu\u00e9e Jeanne Vinas. Les 25 personnes pr\u00e9sentent ont contribu\u00e9 \u00e0 cette rencontre fort amicale, certains venaient de loin : Alpes-Maritimes, Gard et m\u00eame de l\u2019Yonne. Au cours de conversations fraternelles les \u00e9changes concernant les recherches en cours ont occup\u00e9 [&hellip;]<\/p>\n","protected":false},"author":249,"featured_media":621,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>Les adh\u00e9rents de la r\u00e9gion Sud-est se sont r\u00e9unis pour la 4<sup>\u00e8me<\/sup> ann\u00e9e cons\u00e9cutive chez leur d\u00e9l\u00e9gu\u00e9e Jeanne Vinas. Les 25 personnes pr\u00e9sentent ont contribu\u00e9 \u00e0 cette rencontre fort amicale, certains venaient de loin : Alpes-Maritimes, Gard et m\u00eame de l\u2019Yonne. Au cours de conversations fraternelles les \u00e9changes concernant les recherches en cours ont occup\u00e9 une grande partie de la journ\u00e9e. Il est si rare de pourvoir parler sans contrainte avec la certitude d\u2019\u00eatre compris !<\/p><p>Un repas au restaurant et une visite au palais des bonbons (http:\/\/www.palais-bonbons.com). pour la convivialit\u00e9 et la distraction, puis h\u00e9las les au revoir et l\u2019attente avant la prochaine r\u00e9union chez Jeanne le 15 juin 2013.<\/p><p><em>Quelques t\u00e9moignages :<\/em><\/p><p>Un grand merci pour votre accueil chaleureux et g\u00e9n\u00e9reux. Superbe rencontre. Encore Merci. <em>Pascal<\/em>.<\/p><p>Encore mille fois merci pour votre accueil et votre g\u00e9n\u00e9rosit\u00e9. La journ\u00e9e d\u2019hier \u00e9tait vraiment superbe et tr\u00e8s r\u00e9ussie. Bravo pour l\u2019organisation. Toutes les personnes pr\u00e9sentes \u00e9taient tr\u00e8s int\u00e9ressantes et l\u2019histoire de chacune est tr\u00e8s \u00e9mouvante. Nous sommes ravis de ces bons moments pass\u00e9s ensemble. A bient\u00f4t. Bien amicalement. <em>Philippe et Marie-Fran\u00e7oise<\/em><\/p><p>Merci pour cet accueil si chaleureux. <em>Fernande<\/em><\/p><p><img class=\" size-full wp-image-621\" title=\"120811LQ050A\" src=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2012\/08\/120811LQ050A.jpg\" alt=\"120811LQ050A\" width=\"500\" height=\"399\" border=\"1\" \/><\/p><p><img src=\"file:\/\/\/D:\/Pro\/Projets%20Internet\/Sites\/CSF\/_offline\/120826\/120811LQ051A.jpg\" width=\"100%\" border=\"0\" \/><\/p>","_et_gb_content_width":"","footnotes":""},"categories":[154,13],"tags":[],"class_list":["post-622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rencontres-regionales","category-vie-de-lassociation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9union Montilienne - CSF - HOG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9union Montilienne - CSF - HOG\" \/>\n<meta property=\"og:description\" content=\"Les adh\u00e9rents de la r\u00e9gion Sud-est se sont r\u00e9unis pour la 4\u00e8me ann\u00e9e cons\u00e9cutive chez leur d\u00e9l\u00e9gu\u00e9e Jeanne Vinas. Les 25 personnes pr\u00e9sentent ont contribu\u00e9 \u00e0 cette rencontre fort amicale, certains venaient de loin : Alpes-Maritimes, Gard et m\u00eame de l\u2019Yonne. Au cours de conversations fraternelles les \u00e9changes concernant les recherches en cours ont occup\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/\" \/>\n<meta property=\"og:site_name\" content=\"CSF - HOG\" \/>\n<meta property=\"article:published_time\" content=\"2012-08-26T12:48:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-05T14:09:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2012\/08\/120811LQ050A.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"399\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GOFFIN Alexandre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"GOFFIN Alexandre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/vie-de-lassociation\\\/rencontres-regionales\\\/reunion-montilienne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/vie-de-lassociation\\\/rencontres-regionales\\\/reunion-montilienne\\\/\"},\"author\":{\"name\":\"GOFFIN Alexandre\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#\\\/schema\\\/person\\\/19507754554eb5218427fc31038cac56\"},\"headline\":\"R\u00e9union Montilienne\",\"datePublished\":\"2012-08-26T12:48:39+00:00\",\"dateModified\":\"2017-10-05T14:09:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/vie-de-lassociation\\\/rencontres-regionales\\\/reunion-montilienne\\\/\"},\"wordCount\":254,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/vie-de-lassociation\\\/rencontres-regionales\\\/reunion-montilienne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/120811LQ050A.jpg\",\"articleSection\":[\"Rencontres r\u00e9gionales\",\"Vie de l'Association\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/vie-de-lassociation\\\/rencontres-regionales\\\/reunion-montilienne\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/vie-de-lassociation\\\/rencontres-regionales\\\/reunion-montilienne\\\/\",\"url\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/vie-de-lassociation\\\/rencontres-regionales\\\/reunion-montilienne\\\/\",\"name\":\"R\u00e9union Montilienne - CSF - HOG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/vie-de-lassociation\\\/rencontres-regionales\\\/reunion-montilienne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/vie-de-lassociation\\\/rencontres-regionales\\\/reunion-montilienne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/120811LQ050A.jpg\",\"datePublished\":\"2012-08-26T12:48:39+00:00\",\"dateModified\":\"2017-10-05T14:09:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#\\\/schema\\\/person\\\/19507754554eb5218427fc31038cac56\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/vie-de-lassociation\\\/rencontres-regionales\\\/reunion-montilienne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/vie-de-lassociation\\\/rencontres-regionales\\\/reunion-montilienne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/vie-de-lassociation\\\/rencontres-regionales\\\/reunion-montilienne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/120811LQ050A.jpg\",\"contentUrl\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/120811LQ050A.jpg\",\"width\":500,\"height\":399,\"caption\":\"120811LQ050A\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/vie-de-lassociation\\\/rencontres-regionales\\\/reunion-montilienne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9union Montilienne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/\",\"name\":\"C\u0153urs sans fronti\u00e8res\",\"description\":\"Association franco-allemande des Enfants de la Seconde Guerre Mondiale\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.coeurssansfrontieres.com\\\/fr\\\/#\\\/schema\\\/person\\\/19507754554eb5218427fc31038cac56\",\"name\":\"GOFFIN Alexandre\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9union Montilienne - CSF - HOG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9union Montilienne - CSF - HOG","og_description":"Les adh\u00e9rents de la r\u00e9gion Sud-est se sont r\u00e9unis pour la 4\u00e8me ann\u00e9e cons\u00e9cutive chez leur d\u00e9l\u00e9gu\u00e9e Jeanne Vinas. Les 25 personnes pr\u00e9sentent ont contribu\u00e9 \u00e0 cette rencontre fort amicale, certains venaient de loin : Alpes-Maritimes, Gard et m\u00eame de l\u2019Yonne. Au cours de conversations fraternelles les \u00e9changes concernant les recherches en cours ont occup\u00e9 [&hellip;]","og_url":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/","og_site_name":"CSF - HOG","article_published_time":"2012-08-26T12:48:39+00:00","article_modified_time":"2017-10-05T14:09:42+00:00","og_image":[{"width":500,"height":399,"url":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2012\/08\/120811LQ050A.jpg","type":"image\/jpeg"}],"author":"GOFFIN Alexandre","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"GOFFIN Alexandre","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/#article","isPartOf":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/"},"author":{"name":"GOFFIN Alexandre","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#\/schema\/person\/19507754554eb5218427fc31038cac56"},"headline":"R\u00e9union Montilienne","datePublished":"2012-08-26T12:48:39+00:00","dateModified":"2017-10-05T14:09:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/"},"wordCount":254,"commentCount":0,"image":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2012\/08\/120811LQ050A.jpg","articleSection":["Rencontres r\u00e9gionales","Vie de l'Association"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/","url":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/","name":"R\u00e9union Montilienne - CSF - HOG","isPartOf":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/#primaryimage"},"image":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2012\/08\/120811LQ050A.jpg","datePublished":"2012-08-26T12:48:39+00:00","dateModified":"2017-10-05T14:09:42+00:00","author":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#\/schema\/person\/19507754554eb5218427fc31038cac56"},"breadcrumb":{"@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/#primaryimage","url":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2012\/08\/120811LQ050A.jpg","contentUrl":"https:\/\/www.coeurssansfrontieres.com\/wp-content\/uploads\/2012\/08\/120811LQ050A.jpg","width":500,"height":399,"caption":"120811LQ050A"},{"@type":"BreadcrumbList","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/vie-de-lassociation\/rencontres-regionales\/reunion-montilienne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.coeurssansfrontieres.com\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9union Montilienne"}]},{"@type":"WebSite","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#website","url":"https:\/\/www.coeurssansfrontieres.com\/fr\/","name":"C\u0153urs sans fronti\u00e8res","description":"Association franco-allemande des Enfants de la Seconde Guerre Mondiale","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coeurssansfrontieres.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.coeurssansfrontieres.com\/fr\/#\/schema\/person\/19507754554eb5218427fc31038cac56","name":"GOFFIN Alexandre"}]}},"_links":{"self":[{"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/posts\/622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/users\/249"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/comments?post=622"}],"version-history":[{"count":0,"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/posts\/622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/media\/621"}],"wp:attachment":[{"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/media?parent=622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/categories?post=622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coeurssansfrontieres.com\/fr\/wp-json\/wp\/v2\/tags?post=622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}